{"id":2690,"date":"2017-05-24T10:19:55","date_gmt":"2017-05-24T08:19:55","guid":{"rendered":"http:\/\/www.ukclub.it\/?p=2690"},"modified":"2024-10-09T09:02:17","modified_gmt":"2024-10-09T07:02:17","slug":"ukclub-kalaban-diamo-un-calcio-alle-distanze","status":"publish","type":"post","link":"https:\/\/www.ukclub.it\/index.php\/ukclub-kalaban-diamo-un-calcio-alle-distanze\/","title":{"rendered":"UkClub Kalaban &#8211; Diamo un calcio alle distanze"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Davide Vittori, tecnico di 33 anni di Martinengo, \u00e8 stato trovato senza vita nel suo letto sabato 2 gennaio. Era molto conosciuto in paese per essere anche mus<\/em><span class=\"text_exposed_show\"><em>icista, allenatore di calcio e impegnato nel volontariato con progetti di sostegno a distanza per la popolazione del Mali,<\/em>&nbsp;cos\u00ec riportava <\/span><a href=\"https:\/\/www.ecodibergamo.it\/stories\/bassa-bergamasca\/trovato-morto-in-casa-a-33-annimartinengo-piange-davide-vittori_1159298_11\/\">l&#8217;Eco di Bergamo del 3 gennaio 2016<\/a>.<\/p>\n<\/blockquote>\n\n\n\n<p>Quel giorno fin\u00ec la vita di un ragazzo, di un giovane uomo,ma i suoi progetti, i suoi ideali, le sue speranze continuarono. <span style=\"font-size: revert; color: initial; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Nasce quindi la squadra di calcio <a href=\"https:\/\/www.facebook.com\/people\/Uk-club-Kalaban\/100064021596605\/\" target=\"_blank\" rel=\"noreferrer noopener\">UkClub Kalaban<\/a> in sua memoria e in onore di tutti coloro che portano avanti l&#8217;<strong>Associazione UkClub<\/strong> &#8211; che siete tutti voi.<\/span><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Da dove nasce l&#8217;idea<\/h3>\n\n\n\n<div class=\"text_exposed_show\">\n<p>Nel quartiere dove nell&#8217;estate 2012 inizi\u00f2 l&#8217;esperienza africana del nostro compagno Davide, viene cos\u00ec fondato l&#8217;<strong>UkClub Kalaban<\/strong>, grazie all&#8217;iniziativa di alcuni nostri amici e il supporto dei volontari di <strong>UnAltroMondo OdV<\/strong>&nbsp;sul posto. A questo progetto siamo molto legati, sia per la passione del calcio che universalmente ci accomuna, ma soprattutto per l&#8217;importanza che questo tipo di iniziative possono avere su questi ragazzi del quartiere dove operiamo con altri progetti. Avere un obiettivo, delle motivazioni, sentirsi parte di un gruppo, o semplicemente non restare in strada alla merc\u00e9 di tutto, ha un impatto sociale notevolissimo. I ragazzi coinvolti ora sono circa una trentina e continueremo a portare avanti questa che \u00e8, almeno secondo, una delle azioni pi\u00f9 colorate che abbiamo iniziato.<\/p>\n<h3>Perch\u00e9?<\/h3>\n<p>Principale scopo della formazione della squadra \u00e8 di togliere i ragazzini dalla strada e farli uscire dall&#8217;ambiente degradato della periferia dove vivono, spesso abbandonati a se stessi a livello famigliare, creare occasioni di aggregazione e inclusione civile, sportiva e culturale, e farli sentire parte integrante del territorio. Provenienti da famiglie molto povere di Kalaban Coura, iscritti in diverse scuole del quartiere, a tutti i ragazzi della squadra viene richiesta la&nbsp;<strong>regolare frequenza delle lezioni<\/strong>, e il raggiungimento delle medie necessarie per la promozione di fine anno.<\/p>\n<h3>2017<\/h3>\n<p>Con il ben sonante nome di UkClub Kalaban, una preselezione di circa una quarantina di ragazzini dai 9 ai 13 anni del quartiere da inizio ad una nuova avventura con la formazione di una squadra di calcio giovanile. Si susseguono allenamenti quotidiani e prime partite amichevoli contro formazioni scolastiche coetanee del quartiere, sotto la guida del loro coach, Mamadou. Tra le prime squadre incontrate anche quella della nostra scuola umanista Silo, gi\u00e0 campione nel settore giovanile scolastico di quartiere, risultata (prevedibilmente!) vincente in questo esordio.<img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2017-01-prima-formazione-volontariato-africa-mali-milano.jpg\" alt=\"Prima Formazione della Squdra di calcio UKClub Kalaban Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\"\/><\/p>\n<p>C&#8217;\u00e8 ancora tanta strada da fare, ma l&#8217;entusiasmo dei ragazzini del neonato UKClub Kalaban \u00e8 enorme.<br \/>Una raccolta di immagini dei primi incontri sono riassunti in questo&nbsp;<a href=\"http:\/\/www.facebook.com\/uamonlus\/photos?tab=album&amp;album_id=1220703894679863\" target=\"_blank\" rel=\"noreferrer noopener\">album su Facebook<\/a>.<\/p>\n<p>La squadra sta crescendo, nonostante si siano incassate sconfitte su sconfitte, ma i ragazzi sono tosti. Riescono nell&#8217;estate del 2017 a conquistare il primo torneo di quartiere. Riusciamo poi dall&#8217;Italia a spedire i primi completi ufficiali con tanto di logo e accessori al seguito, mentre in Mali il coach instancabile continua ad allenare i suoi ragazzi giorno per giorno. <img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2018-01-avversario-Silo-volontariato-africa-mali-milano.jpg\" alt=\"La squadra Silo di Bamako, Mali - UnAltroMondo Onlus associazione di volontariato MIlano\"\/><\/p>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">2018<\/h3>\n\n\n\n<p>Passano i mesi, si organizzano partite su partite, si incassano sconfitte su sconfitte, ma la squadra cresce, inizia a vincere qualche match e infine arriva prima classificata in un torneo di quartiere. Per la ricorrenza del secondo anniversario della morte di Davide, UK Club Kalaban vince inoltre con un clamoroso 5 &#8211; 1 sull&#8217;avversario pi\u00f9 temuto, la squadra della nostra Scuola Umanista Silo. <span style=\"font-size: revert; color: initial; font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, Oxygen-Sans, Ubuntu, Cantarell, 'Helvetica Neue', sans-serif;\">Per rendere il team pi\u00f9 autonomo, i nostri volontari costruiscono due porte\u2026 portatili, perch\u00e9 non tutti i campi di calcio ne sono provvisti!&nbsp;<\/span><\/p>\n\n\n\n<p>Durante i mesi estivi la squadra ha partecipato a diverse competizioni locali. Tra le partite amichevoli la seconda edizione dell&#8217;incontro con i ragazzi di strada seguiti dal nostro Centro di accoglienza OASIS. Ragazzi decisamente pi\u00f9 grandi dell&#8217;altra volta, ma ugualmente sconfitti dal team UK Club Kalaban che sta migliorando l&#8217;impegno e l&#8217;entusiasmo di match in match. Importante vincita anche quella ottenuta nella finale seppur ai rigori nel torneo che ha visto diversi quartieri della capitale a contendersi il trofeo nella categoria 45 kg.<img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2018-03-prima-giocatrice-volontariato-africa-mali-milano.jpg\" alt=\"Prima giocatrice della squadra di calcio UKClub Kalaban Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\"\/><\/p>\n\n\n\n<p>Per quanto riguarda il rendimento scolastico, tutti i ragazzi sono stati promossi, e tutti i candidati che si sono presentati all&#8217;esame di scuola fondamentale sono riusciti a ottenere il diploma. Novit\u00e0 della stagione l&#8217;inserimento della prima ragazza nella squadra! L&#8217;anno finisce con la chiusura della campagna raccolta scarpe da calcio per il Mali lanciata in occasione della nostra festa del sostegno a distanza di fine ottobre e durante un&#8217;analoga iniziativa promossa dai nostri volontari in Germania.<br \/>A parte le nuove calzature acquistate ad hoc con i fondi in denaro raccolti, grazie all&#8217;intervento degli amici di UK Club Martinengo abbiamo ricevute altre centinaia di paia di scarpe da calcio nuove e usate. Anche se non sar\u00e0 possibile portarle tutte subito in Mali per Natale, una volte arrivate, rappresenteranno un bel regalo per tanti ragazzi dai piedi scalzi!<img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2018-05-partite-amichevoli-volontariato-africa-mali-milano.jpg\" alt=\"Partita amichevole della Squdra di calcio UKClub Kalaban Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\"\/><\/p>\n\n\n\n<p>Nel programma di recupero dei ragazzi di strada portato avanti da diversi anni dal&nbsp;<a href=\"https:\/\/unaltromondo.it\/loasis-centro-di-ascolto-per-giovani-in-difficolta-mali\/\" data-type=\"post\" data-id=\"238\">Centro di Ascolto l\u2019OASIS<\/a>&nbsp;si organizzano periodicamente incontri amichevoli al fine di favorire il loro reinserimento sociale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2019<\/h3>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Sanbara - Giochiamo a calcio con UK!Club Kalaban\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/b8IUmKHW3AQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Finalmente giunte a destinazione! Con l&#8217;arrivo dei primi volontari di UnAltroMondo in missione a Bamako \u00e8 sbarcata anche la prima valigia piena di scarpe da calcio per la nostra squadra, per la massima gioia dei nostri giovani giocatori. Un grande grazie a chi le ha cedute, e a chi le ha raccolte!<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mali 2019 - UK Club Martinengo\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/46YYBoECOck?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>A pochi giorni dallo straordinario mega-evento&nbsp;<strong>!U.k Dave<\/strong>, la festa in memoria di Davide,<br \/>anche Bamako ha voluto ricordare il nostro volontario e amico di Martinengo con due tornei di calcio svoltisi in contemporanea e conclusosi con un gran finale in presenza dei nostri volontari sul posto per i campi di lavoro estivi: la Coppa Davide Vittori, che ha visto la squadra locale FC Allaye vincere per la seconda volta, e un torneo commemorativo locale. Anche se i ragazzini della nostra squadra si sono dovuti accontentare del secondo posto, \u00e8 stata una bella festa che ha visto un grande coinvolgimento di tutta la giovent\u00f9 di quartiere.<\/p>\n\n\n\n\n\n<p>Con l&#8217;inizio del nuovo anno scolastico, anche i ragazzi della nostra squadra di calcio hanno ricevuto un&nbsp;<strong>piccolo kit scolastico<\/strong>: borsette, astucci, matite, gomma, biro e quaderni per aiutare le famiglie e per ricordare che lo studio \u00e8 importante. Una delle condizioni per i piccoli membri della squadra \u00e8 infatti un buon rendimento scolastico, niente bocciature, frequentazione regolare delle lezioni e tempo da dedicare allo studio. Durante la distribuzione dei kit si \u00e8 colta l&#8217;occasione di incontrare i genitori per metterli al corrente delle varie iniziative e per chiedere il loro consenso e il loro coinvolgimento nelle attivit\u00e0 dei loro figli, scolastiche o sportive che siano. L&#8217;affluenza \u00e8 stata sorprendente, l&#8217;apprezzamento per l&#8217;iniziativa unanime e la soddisfazione dei nostri volontari grande.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2019-03-distribuzione-kit-scolastici-volontariato-africa-mali-milano.jpg\" alt=\"Distribuzione dei kit scolastici per la UKClub Kalaban Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\" class=\"wp-image-877\"\/><\/figure>\n\n\n\n<p>Per vedere altre immagini dell&#8217;incontro con i genitori visita la&nbsp;<a href=\"https:\/\/www.facebook.com\/uamonlus\/photos?tab=album&amp;album_id=2481679688582271\">nostra galleria su Facebook<\/a>.<\/p>\n\n\n\n<p>Dal 2019 anche la nostra squadra ha diritto all\u2019uso di una parte del grande terreno sportivo polivalente allestito dal Comune di Kalaban a favore delle sue associazioni giovanili. L\u2019appezzamento \u00e8 stato concesso in cambio del livellamento e della pulizia dello stesso, lavori effettuati con grande slancio da parte di tutti i componenti della squadra e completati con l&#8217;installazione di porte da calcio fisse.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2020<\/h3>\n\n\n\n<p>L\u2019anno inizia con la distribuzione di&nbsp;<strong>nuovi completi da calcio<\/strong>&nbsp;donati dalla Atletico Meda Sud, associazione sportiva dilettantistica che ha lanciato una campagna di raccolta di tute non pi\u00f9 in uso dai loro ragazzi ma preziosissime per i nostri piccoli calciatori e indossate non solo in occasione degli allenamenti.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClub-Kalaban-2020-01-magliette-atletica-Meda-volontariato-africa-mali-milano.jpg\" alt=\"Magliette dell'atletica Meda a Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\" class=\"wp-image-883\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2020-02-vincitori-coppa-Davide-volontariato-africa-mali-milano.jpg\" alt=\"Vincitori della Coppa Davide Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\" class=\"wp-image-881\"\/><\/figure>\n\n\n\n<p>Dopo il lungo arresto di allenamenti, attivit\u00e0 agonistiche e partite amichevoli (dal 19 marzo, giorno dell&#8217;inizio del lockdown in Mali, fino al 23 maggio, data della fine del periodo di Ramadan), UKClubKalaban \u00e8 nuovamente tornato vincente in campo in occasione dell&#8217;annuale&nbsp;<strong>Memorial<\/strong>&nbsp;dedicato a&nbsp;<strong>Davide Vittori<\/strong>. Anche se \u00e8 mancato il supporto dei volontari italiani assenti a causa del COVID-19 a fare il tifo e incitare la nostra squadra, i ragazzi si sono battuti con orgoglio e tenacia aggiudicandosi la coppa superando il FC Jambar 2:1 e portando a casa anche la medaglia per il miglior giocatore. Ringraziamo UK Club Martinengo che ha reso possibile realizzare l&#8217;evento, Coach Mamadou che ha portato la nostra squadra alla vittoria, i nostri partner in loco, gli infaticabili piccoli giocatori, ma soprattutto Davide che continua a ispirare questi giovani e questa comunit\u00e0!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2021<\/h3>\n\n\n\n<p>l nuovo anno riparte in memoria del nostro volontario Davide che ci ha lasciato 5 anni fa, ma che continua a vivere nei nostri cuori e in quelli dei bambini maliani.<br \/>Per onorare il suo impegno a favore dei giovani&nbsp;<strong>nello sport e nell&#8217;istruzione<\/strong>&nbsp;abbiamo nuovamente distribuito dei kit scolastici (<a href=\"https:\/\/www.facebook.com\/uamonlus\/posts\/3701270579956503\">vedi post su Facebook<\/a>) \u2013 come d\u2019abitudine si fa con i bambini sostenuti a distanza &#8211; anche ai ragazzi della squadra di calcio, in occasione della riapertura delle scuole che hanno ripreso le attivit\u00e0 didattiche regolari a gennaio anche in Mali, dopo vari periodi di lockdown, scioperi e le vacanza di Natale.<br \/>Ringraziamo Davide e gli amici di&nbsp;<a href=\"https:\/\/www.ukclub.it\/\">UkClub Martinengo<\/a>&nbsp;che portano avanti questo progetto insieme a noi.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2021-01-kit-scolastici-volontariato-africa-mali-milano.jpg\" alt=\"Kit scolastici per la UKClub Kalaban Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\" class=\"wp-image-887\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2021-02-schieramento-squadre-volontariato-africa-mali-milano.jpg\" alt=\"Coppa Davide Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\" class=\"wp-image-888\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2021-03-campo-comunale-volontariato-africa-mali-milano.jpg\" alt=\"Campo comunale di Kalaban Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\" class=\"wp-image-889\"\/><\/figure>\n\n\n\n<p>A giungo si \u00e8 svolto l\u2019importante partita in memoria di Davide in occasione del suo compleanno.<br \/>I nostri volontari, arrivati dall&#8217;Italia giusto in tempo per il match, hanno potuto assistere ad una strepitosa vincita della nostra squadra contro gli avversari di sempre, battuti 7 a 0! L\u2019incontro si \u00e8 svolto sul campo di calcio riservato proprio a UkClub Kalaban nella grande area polisportiva del Comune.<br \/>Il match \u00e8 stato registrata con videocamera e ripreso in parte anche con il drone. Alcune delle immagini pi\u00f9 belle si possono vedere nel video sotto.<\/p>\n\n\n\n<p>Ringraziamo&nbsp;<strong>Coach Mamadou<\/strong>&nbsp;e i suoi due nuovi assistenti. Un sentito grazie va anche alla Polisportiva Nova e all&#8217;Atletico Meda per le tute da calcio donate, orgogliosamente sfoggiate da parte dei piccoli aspiranti campioni che hanno accompagnato i nostri calciatori in campo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Coppa Davide 2021 - Calcio per i Bambini in Mali\" width=\"780\" height=\"439\" src=\"https:\/\/www.youtube.com\/embed\/Sfigv2JvATQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Per la stagione calcistica 2021\/2022 servono magliette nuove: piccoli calciatori crescono e occorre fornire la squadra di tute su misura a un prezzo abbordabile. Alle fine si scelgono nuovi colori: per i piccoli si riciclano le vecchie tute nere e gialle, mentre d\u2019ora in poi i grandi scendono in campo tinti di rosso.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2021-04-maglie-nuove-volontariato-africa-mali-milano.jpg\" alt=\"UK Club Kalaban Bamako Mali - UnAltroMondo Onlus associazione di volontariato MIlano\" class=\"wp-image-890\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">2022<\/h3>\n\n\n\n<p>L\u2019anno inizia con una splendida giornata di sole per l&#8217;amichevole tra UK Club Kalaban e la squadra ASG di&nbsp;<strong>Kati<\/strong>, organizzata dal nostro amico&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.radiochico.ch\/radiochico-auslandkorrespondenten\/souleymane-guindo-mali\/\" target=\"_blank\">Souleymane<\/a>, radioreporter di&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.radiochico.ch\/\" target=\"_blank\">RadioChico Svizzera<\/a>.<br \/>La partita \u00e8 finita ai rigori a favore della squadra di casa, dopo un bel 2:2 equilibrato. Un po&#8217; di tristezza per i nostri ragazzi di UK Club Kalaban, ma alla fine \u00e8 stata una bella trasferta con tante nuove conoscenze e tante emozioni.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2022-01-trasferta-Kati-volontariato-africa-mali-milano.jpg\" alt=\"Trasferta della Squdra di calcio UKClub Kalaban Bamako Mali - UnAltroMondo Onlus associazione di volontariato Sesto SG MIlano\" class=\"wp-image-893\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2022-02-squadre-avversarie-Kati-volontariato-africa-mali-milano.jpg\" alt=\"Squdra di calcio Kati Mali - UnAltroMondo Onlus associazione di volontariato Sesto SG MIlano\" class=\"wp-image-894\"\/><\/figure>\n\n\n\n<p>Mentre allenamenti, partite amichevoli e tornei di quartiere continuano a scadenza regolare, stiamo cercando di perfezionare le pratiche per l<strong>\u2019iscrizione all\u2019associazione calcistica nazionale<\/strong>, che garantirebbe una maggiore visibilit\u00e0, la possibilit\u00e0 di competere a livelli superiori non occasionali e di avere accessi ai campi di gioco convenzionati.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2022-03-coppa-Davide-vincitori-volontariato-africa-mali-milano.jpg\" alt=\"Squadra di calcio Uk Club Kalaban vincitore trofeo Davide\" class=\"wp-image-1143\"\/><\/figure>\n\n\n\n<p>L&#8217;annuale coppa Davide si tiene in presenza dei nostri volontari in visita a Bamako sotto&nbsp;una pioggia torrenziale. Tuttavia, vento e acqua non hanno impedito alla nostra squadra di portare a casa l&#8217;ambito trofeo.<\/p>\n\n\n\n<p>Alla fine dell&#8217;estate alcuni volontari locali iniziano un programma di atletica preparativa per i giovani del quartiere con l&#8217;intento di torglierli dalla strada migliorando la qualit\u00e0 del loro tempo libero, e viene creata una squadra femminile che esce vincitrice gi\u00e0 nel suo primo torneo.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2022-04-squadra-femminile.jpeg\" alt=\"Squadra femminile UK Club Kalaban di Bamako, Mali\" class=\"wp-image-1407\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/unaltromondo.it\/wp-content\/uploads\/2022\/06\/UkClubKalaban-2022-03-squadra-femminile.jpg\" alt=\"Squadra di calcio Femminile Uk Club Kalaban\" class=\"wp-image-1144\"\/><figcaption class=\"wp-element-caption\">Squadra femminile UkClub Kalaban<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Davide Vittori, tecnico di 33 anni di Martinengo, \u00e8 stato trovato senza vita nel suo letto sabato 2 gennaio. Era molto conosciuto in paese per essere anche musicista, allenatore di calcio e impegnato nel volontariato con progetti di sostegno a distanza per la popolazione del Mali,&nbsp;cos\u00ec riportava l&#8217;Eco di Bergamo del 3 gennaio 2016. Quel giorno fin\u00ec la vita di &hellip; <\/p>\n","protected":false},"author":3,"featured_media":2716,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[57,55],"tags":[],"class_list":["post-2690","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-progetti","category-slider","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/posts\/2690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/comments?post=2690"}],"version-history":[{"count":15,"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/posts\/2690\/revisions"}],"predecessor-version":[{"id":3089,"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/posts\/2690\/revisions\/3089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/media\/2716"}],"wp:attachment":[{"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/media?parent=2690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/categories?post=2690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ukclub.it\/index.php\/wp-json\/wp\/v2\/tags?post=2690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}